{"id":6900,"date":"2023-03-10T12:49:43","date_gmt":"2023-03-10T11:49:43","guid":{"rendered":"https:\/\/elsur-racing.de\/?p=6900"},"modified":"2023-03-10T12:49:43","modified_gmt":"2023-03-10T11:49:43","slug":"fruehjahrsupdate-gestuet-rennstall-zucht","status":"publish","type":"post","link":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/","title":{"rendered":"Fr\u00fchjahrsupdate &#8211; Gest\u00fct &#8211; Rennstall &#8211; Zucht"},"content":{"rendered":"<p>Die letzten Wochen haben Einiges an Bewegung gebracht:<\/p>\n<p>Im Gest\u00fct gehen die Arbeiten mit Vollgas voran, das Wohn- und Verwaltungsgeb\u00e4ude ist fast fertiggestellt, beim Innenausbau laufen die letzten Arbeiten. Dar\u00fcber hinaus sind eine Lagerhalle und unser \u00abEckstall\u00bb mit Kapazit\u00e4t f\u00fcr 20 Boxen im Rohbau entstanden. In den n\u00e4chsten Wochen folgen noch der Rundstall und die Bewegungshalle mit F\u00fchranlage.<\/p>\n<p>Unsere Maidenstuten sind auf die Hengst-Gest\u00fcte verteilt:<br \/>\n<strong>La Estrellita<\/strong> hat sich im Haras du Logis gut eingelebt und soll von Cloth of Stars gedeckt werden.<br \/>\n<strong>Wonderful Starlet<\/strong> und <strong>Flashing Starlet<\/strong> haben Quartier im Gest\u00fct F\u00e4hrhof bezogen und gehen zu Alson.<br \/>\n<strong>Ablaze<\/strong> ist wohlbehalten im Gest\u00fct L\u00fcnzen bei Best Solution angekommen.<br \/>\n<strong>Pop Starlet<\/strong> ist tragend von Alson im Gest\u00fct Hoheneichen, wo wir alle gespannt auf den nahenden Abfohltermin hin fiebern!<\/p>\n<p>Im Rennstall werden folgende Kandidatinnen auf die kommende Saison vorbereitet:<br \/>\n<strong>Gerald Geisler<\/strong>, hat dieses Jahr unser gr\u00f6\u00dftes Lot. Neben unserer 4-j\u00e4hrigen <strong>Queen of Starlets<\/strong> (v. Brametot), sind seit einer Woche die beiden 2-J\u00e4hrigen, <strong>New Starlet<\/strong> (v. Harzand) und <strong>Tanami Starlet<\/strong> (v. Best Solution), in Iffezheim eingezogen. Beide Stuten wurden bisher im Gest\u00fct L\u00fcnzen angeritten und auf ihre zuk\u00fcnftige Karriere im Rennstall vorbereitet.<\/p>\n<p>3 weitere Starlets bereiten sich in M\u00fcnchen auf die kommende Saison vor:<br \/>\n<strong>Northern Starlet<\/strong> (v. Ruler of the World) steht bei <strong>Michael Figge<\/strong> im Training. Hier ist auch f\u00fcr unsere \u00abM\u00e4nner-Besitzergemeinschaft\u00bb, Stall O&#8217;Zapft is, <strong>Freibier <\/strong>(v. Ito) im Training.<br \/>\n<strong>Paris Starlet<\/strong> (v. Lord of England) steht f\u00fcr unsere Interessen bei <strong>Karoly Kerekes<\/strong> in Vorbereitung auf die Rennpferdekarriere.<br \/>\nNicht zu vergessen , unsere Hoffnung, <strong>Quijana Starlet<\/strong> (v. Highland Reel), die der <strong>Galoppclub S\u00fcddeutschland<\/strong> bei <strong>Werner Glanz<\/strong> im Training hat.<\/p>\n<p>Die Daumen sind gedr\u00fcckt! Hals &amp; Bein f\u00fcr Zucht- und Rennsaison 2023!<\/p>\n<p>Sie waren noch nie in einem Rennstall und w\u00fcrden das gerne mal live erleben? Am 15.04.23 haben Sie bundesweit die Chance einmal hinter die Kulissen im Galoppsport zu schauen. Termine und (kostenlose) Registrierung unter: <a href=\"http:\/\/www.tag-der-rennstaelle.de\">www.tag-der-rennstaelle.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die letzten Wochen haben Einiges an Bewegung gebracht: Im Gest\u00fct gehen die Arbeiten mit Vollgas voran, das Wohn- und Verwaltungsgeb\u00e4ude ist fast fertiggestellt, beim Innenausbau laufen die letzten Arbeiten. Dar\u00fcber hinaus sind eine Lagerhalle und unser \u00abEckstall\u00bb mit Kapazit\u00e4t f\u00fcr 20 Boxen im Rohbau entstanden. In den n\u00e4chsten Wochen folgen noch der Rundstall und die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[34,39,35],"tags":[222,223,105,251,266,267,128,106,293,176,355,107,252,360,227,109,294],"class_list":["post-6900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreras","category-general","category-semental","tag-best-solution-es","tag-deutscher-galopp-es","tag-el-sur-racing-es","tag-el-sur-stud-es","tag-faehrhof-es","tag-galoppclub-sueddeutschland-es","tag-galopprennsport-es","tag-galoppsport-es","tag-gestuet-hoheneichen-es","tag-gestuet-luenzen-es","tag-gestuet-sachsenburg-es","tag-horseracing-es","tag-trainer-gerald-geisler-es","tag-trainer-karoly-kerekes-es","tag-trainer-michael-figge-es","tag-vollblueter-es","tag-vollblutzucht-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fr\u00fchjahrsupdate - Gest\u00fct - Rennstall - Zucht - ElSur - RACING<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fr\u00fchjahrsupdate - Gest\u00fct - Rennstall - Zucht - ElSur - RACING\" \/>\n<meta property=\"og:description\" content=\"Die letzten Wochen haben Einiges an Bewegung gebracht: Im Gest\u00fct gehen die Arbeiten mit Vollgas voran, das Wohn- und Verwaltungsgeb\u00e4ude ist fast fertiggestellt, beim Innenausbau laufen die letzten Arbeiten. Dar\u00fcber hinaus sind eine Lagerhalle und unser \u00abEckstall\u00bb mit Kapazit\u00e4t f\u00fcr 20 Boxen im Rohbau entstanden. In den n\u00e4chsten Wochen folgen noch der Rundstall und die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/\" \/>\n<meta property=\"og:site_name\" content=\"ElSur - RACING\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/elsurracing\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T11:49:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elsur-racing.de\/wp-content\/uploads\/2023\/03\/MaerzBlog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1564\" \/>\n\t<meta property=\"og:image:height\" content=\"1564\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jochenS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jochenS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/\"},\"author\":{\"name\":\"jochenS\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#\\\/schema\\\/person\\\/194a5e823490b8d996315c19ce22e0b2\"},\"headline\":\"Fr\u00fchjahrsupdate &#8211; Gest\u00fct &#8211; Rennstall &#8211; Zucht\",\"datePublished\":\"2023-03-10T11:49:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elsur-racing.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MaerzBlog.jpg\",\"keywords\":[\"Best Solution\",\"Deutscher Galopp\",\"El Sur Racing\",\"El Sur Stud\",\"F\u00e4hrhof\",\"Galoppclub S\u00fcddeutschland\",\"Galopprennsport\",\"Galoppsport\",\"Gest\u00fct Hoheneichen\",\"Gest\u00fct L\u00fcnzen\",\"Gest\u00fct Sachsenburg\",\"Horseracing\",\"Trainer Gerald Geisler\",\"Trainer Karoly Kerekes\",\"Trainer Michael Figge\",\"Vollbl\u00fcter\",\"Vollblutzucht\"],\"articleSection\":[\"Carreras\",\"General\",\"Semental\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/\",\"url\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/\",\"name\":\"Fr\u00fchjahrsupdate - Gest\u00fct - Rennstall - Zucht - ElSur - RACING\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elsur-racing.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MaerzBlog.jpg\",\"datePublished\":\"2023-03-10T11:49:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elsur-racing.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MaerzBlog.jpg\",\"contentUrl\":\"https:\\\/\\\/elsur-racing.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MaerzBlog.jpg\",\"width\":1564,\"height\":1564,\"caption\":\"El Sur Racing - Q1\\\/2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/2023\\\/03\\\/fruehjahrsupdate-gestuet-rennstall-zucht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina principal\",\"item\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fr\u00fchjahrsupdate &#8211; Gest\u00fct &#8211; Rennstall &#8211; Zucht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/\",\"name\":\"ElSur - RACING\",\"description\":\"elsur -team, -racing, -stud, -horsetransport\",\"publisher\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#organization\",\"name\":\"ElSur - CARRERAS\",\"url\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/elsur-racing.de\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/LogoESPoloRacingStudbw.jpg\",\"contentUrl\":\"https:\\\/\\\/elsur-racing.de\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/LogoESPoloRacingStudbw.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"ElSur - CARRERAS\"},\"image\":{\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/elsurracing\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/#\\\/schema\\\/person\\\/194a5e823490b8d996315c19ce22e0b2\",\"name\":\"jochenS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be1d72a69a8fd0530768b25935c438282455ec00aa59747d82353fed55109023?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be1d72a69a8fd0530768b25935c438282455ec00aa59747d82353fed55109023?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be1d72a69a8fd0530768b25935c438282455ec00aa59747d82353fed55109023?s=96&d=mm&r=g\",\"caption\":\"jochenS\"},\"sameAs\":[\"http:\\\/\\\/www.elsur-racing.de\"],\"url\":\"https:\\\/\\\/elsur-racing.de\\\/es\\\/author\\\/jochens\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fr\u00fchjahrsupdate - Gest\u00fct - Rennstall - Zucht - ElSur - RACING","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/","og_locale":"es_ES","og_type":"article","og_title":"Fr\u00fchjahrsupdate - Gest\u00fct - Rennstall - Zucht - ElSur - RACING","og_description":"Die letzten Wochen haben Einiges an Bewegung gebracht: Im Gest\u00fct gehen die Arbeiten mit Vollgas voran, das Wohn- und Verwaltungsgeb\u00e4ude ist fast fertiggestellt, beim Innenausbau laufen die letzten Arbeiten. Dar\u00fcber hinaus sind eine Lagerhalle und unser \u00abEckstall\u00bb mit Kapazit\u00e4t f\u00fcr 20 Boxen im Rohbau entstanden. In den n\u00e4chsten Wochen folgen noch der Rundstall und die [&hellip;]","og_url":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/","og_site_name":"ElSur - RACING","article_publisher":"https:\/\/www.facebook.com\/elsurracing","article_published_time":"2023-03-10T11:49:43+00:00","og_image":[{"width":1564,"height":1564,"url":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2023\/03\/MaerzBlog.jpg","type":"image\/jpeg"}],"author":"jochenS","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jochenS","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#article","isPartOf":{"@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/"},"author":{"name":"jochenS","@id":"https:\/\/elsur-racing.de\/es\/#\/schema\/person\/194a5e823490b8d996315c19ce22e0b2"},"headline":"Fr\u00fchjahrsupdate &#8211; Gest\u00fct &#8211; Rennstall &#8211; Zucht","datePublished":"2023-03-10T11:49:43+00:00","mainEntityOfPage":{"@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/elsur-racing.de\/es\/#organization"},"image":{"@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#primaryimage"},"thumbnailUrl":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2023\/03\/MaerzBlog.jpg","keywords":["Best Solution","Deutscher Galopp","El Sur Racing","El Sur Stud","F\u00e4hrhof","Galoppclub S\u00fcddeutschland","Galopprennsport","Galoppsport","Gest\u00fct Hoheneichen","Gest\u00fct L\u00fcnzen","Gest\u00fct Sachsenburg","Horseracing","Trainer Gerald Geisler","Trainer Karoly Kerekes","Trainer Michael Figge","Vollbl\u00fcter","Vollblutzucht"],"articleSection":["Carreras","General","Semental"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/","url":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/","name":"Fr\u00fchjahrsupdate - Gest\u00fct - Rennstall - Zucht - ElSur - RACING","isPartOf":{"@id":"https:\/\/elsur-racing.de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#primaryimage"},"image":{"@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#primaryimage"},"thumbnailUrl":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2023\/03\/MaerzBlog.jpg","datePublished":"2023-03-10T11:49:43+00:00","breadcrumb":{"@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#primaryimage","url":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2023\/03\/MaerzBlog.jpg","contentUrl":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2023\/03\/MaerzBlog.jpg","width":1564,"height":1564,"caption":"El Sur Racing - Q1\/2023"},{"@type":"BreadcrumbList","@id":"https:\/\/elsur-racing.de\/es\/2023\/03\/fruehjahrsupdate-gestuet-rennstall-zucht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina principal","item":"https:\/\/elsur-racing.de\/es\/"},{"@type":"ListItem","position":2,"name":"Fr\u00fchjahrsupdate &#8211; Gest\u00fct &#8211; Rennstall &#8211; Zucht"}]},{"@type":"WebSite","@id":"https:\/\/elsur-racing.de\/es\/#website","url":"https:\/\/elsur-racing.de\/es\/","name":"ElSur - RACING","description":"elsur -team, -racing, -stud, -horsetransport","publisher":{"@id":"https:\/\/elsur-racing.de\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elsur-racing.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elsur-racing.de\/es\/#organization","name":"ElSur - CARRERAS","url":"https:\/\/elsur-racing.de\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elsur-racing.de\/es\/#\/schema\/logo\/image\/","url":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2019\/12\/LogoESPoloRacingStudbw.jpg","contentUrl":"https:\/\/elsur-racing.de\/wp-content\/uploads\/2019\/12\/LogoESPoloRacingStudbw.jpg","width":2000,"height":2000,"caption":"ElSur - CARRERAS"},"image":{"@id":"https:\/\/elsur-racing.de\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/elsurracing"]},{"@type":"Person","@id":"https:\/\/elsur-racing.de\/es\/#\/schema\/person\/194a5e823490b8d996315c19ce22e0b2","name":"jochenS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/be1d72a69a8fd0530768b25935c438282455ec00aa59747d82353fed55109023?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be1d72a69a8fd0530768b25935c438282455ec00aa59747d82353fed55109023?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be1d72a69a8fd0530768b25935c438282455ec00aa59747d82353fed55109023?s=96&d=mm&r=g","caption":"jochenS"},"sameAs":["http:\/\/www.elsur-racing.de"],"url":"https:\/\/elsur-racing.de\/es\/author\/jochens\/"}]}},"_links":{"self":[{"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/posts\/6900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/comments?post=6900"}],"version-history":[{"count":4,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/posts\/6900\/revisions"}],"predecessor-version":[{"id":6914,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/posts\/6900\/revisions\/6914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/media\/6896"}],"wp:attachment":[{"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/media?parent=6900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/categories?post=6900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsur-racing.de\/es\/wp-json\/wp\/v2\/tags?post=6900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}